{"id":5241,"date":"2017-09-18T17:39:24","date_gmt":"2017-09-18T15:39:24","guid":{"rendered":"http:\/\/wildtravel.ro\/bird\/tupfelsumpfhuhn-porzana-porzana\/"},"modified":"2017-09-18T17:47:11","modified_gmt":"2017-09-18T15:47:11","slug":"tupfelsumpfhuhn-porzana-porzana","status":"publish","type":"bird","link":"https:\/\/wildtravel.ro\/de\/bird\/tupfelsumpfhuhn-porzana-porzana\/","title":{"rendered":"T\u00fcpfelsumpfhuhn (Porzana porzana)"},"content":{"rendered":"<p>Das <strong>T\u00fcpfelsumpfhuhn<\/strong> (<em>Porzana porzana<\/em>) ist ein Vogel aus der Familie der <a class=\"mw-redirect\" title=\"Rallenv\u00f6gel\" href=\"https:\/\/de.wikipedia.org\/wiki\/Rallenv%C3%B6gel\">Rallenv\u00f6gel<\/a>. Es ist kleiner als eine <a title=\"Wasserralle\" href=\"https:\/\/de.wikipedia.org\/wiki\/Wasserralle\">Wasserralle<\/a> und hat etwa die Gr\u00f6\u00dfe einer <a title=\"Drosseln\" href=\"https:\/\/de.wikipedia.org\/wiki\/Drosseln\">Drossel<\/a>.<\/p>\n<h2><span id=\"Erscheinungsbild\" class=\"mw-headline\">Erscheinungsbild<\/span><\/h2>\n<p>T\u00fcpfelsumpfh\u00fchner haben eine K\u00f6rperl\u00e4nge von etwa 19 bis 22,5 Zentimetern. Von den Wasserrallen k\u00f6nnen sie am einfachsten durch den kurzen, geraden Schnabel unterschieden werden. Dieser ist gelb mit einer roten Basis. Ausgewachsene V\u00f6gel haben eine \u00fcberwiegend braune K\u00f6rperunterseite mit einer blaugrauen Brust. Auf den Flanken sieht man eine fahlgelbe Streifung. Federn des R\u00fcckens und die Federdecken in der Mitte sind schwarz. Das K\u00f6rpergefieder auf der Oberseite verf\u00fcgt au\u00dferdem \u00fcber viele kleine wei\u00dfe Flecke. Die Beine ausgewachsener V\u00f6gel sind von gr\u00fcnlicher Farbe und haben die f\u00fcr Rallen typischen gro\u00dfen Zehen.<\/p>\n<p>Noch nicht ausgewachsene Jungv\u00f6gel gleichen den Altv\u00f6geln; bei ihnen ist jedoch das Brustgefieder noch braun.<\/p>\n<p>Das Verbreitungsgebiet des T\u00fcpfelsumpfhuhns erstreckt sich von Westen und S\u00fcdwesten Europas bis in den S\u00fcden Zentralsibiriens. Einzelne Vorkommen gibt es in Spanien, Italien und Griechenland. Ferner reicht ein geschlossenes Verbreitungsgebiet von der Krim bis zum Kaukasus. Einzelne Verbreitungsgebiete gibt es au\u00dferdem in Mittelasien.<\/p>\n<p>Das T\u00fcpfelsumpfhuhn br\u00fctet in Sumpfgebieten, <a class=\"mw-redirect\" title=\"Niedermoor\" href=\"https:\/\/de.wikipedia.org\/wiki\/Niedermoor\">Niedermooren<\/a> und <a title=\"Seggen\" href=\"https:\/\/de.wikipedia.org\/wiki\/Seggen\">Seggenbest\u00e4nden<\/a> von <a title=\"Europa\" href=\"https:\/\/de.wikipedia.org\/wiki\/Europa\">Europa<\/a> bis <a title=\"Sibirien\" href=\"https:\/\/de.wikipedia.org\/wiki\/Sibirien\">Mittelsibirien<\/a>. Die Nester werden an trockenen Standorten innerhalb dieses Lebensraum angelegt und sind gut versteckt. Meist befinden sie sich dicht \u00fcber dem Boden oder in einer Seggenb\u00fctte. Nester haben gelegentlich ein Dach aus Bl\u00e4ttern. Die Weibchen legen in der Zeit von April bis Juni etwa acht bis 12 Eier von einer gelblichen Grundfarbe, die au\u00dferdem kleine r\u00f6tlichbraune Flecken aufweisen. Die K\u00fcken haben anfangs ein schwarzes Daunenkleid und sind nach etwa 35 bis 42 Tagen flugf\u00e4hig.<\/p>\n<p>&nbsp;<\/p>\n<p>Die \u00dcberwinterungsgebiete liegen in Afrika und Indien.<\/p>\n<h2><span id=\"Nahrung\" class=\"mw-headline\">Nahrung<\/span><\/h2>\n<p>Die T\u00fcpfelsumpfh\u00fchner suchen mit ihren Schn\u00e4beln im Schlamm oder in flachen Gew\u00e4ssern nach Nahrung. Diese besteht \u00fcberwiegend aus Kleintieren wie Insekten, W\u00fcrmern und Schnecken. Sie nehmen auch zarte Pflanzenteile zu sich.<\/p>\n<h2><span id=\"Gef.C3.A4hrdung_.26_Schutzstatus\" class=\"mw-headline\">Gef\u00e4hrdung &amp; Schutzstatus<\/span><\/h2>\n<p>Das T\u00fcpfelsumpfhuhn gilt in Deutschland als &#8222;gef\u00e4hrdet&#8220; (Rote Liste Kat. 3). Es ist eine Art des Anhangs I der EU-Vogelschutzrichtlinie (RL 79\/409\/EWG).<\/p>\n<p>Der Bestand wird f\u00fcr Europa auf 120.000 bis 260.000 Brutpaare gesch\u00e4tzt. L\u00e4nder mit mehr als 20.000 Brutpaaren sind Russland, Wei\u00dfrussland und die Ukraine. Mehr als 2.000 Brutpaare kommen in Estland, Polen und Rum\u00e4nien vor. In Mitteleuropa kommt die Art zwar in allen L\u00e4ndern vor, Polen ist mit einem Brutpaarbestand von 2.500 bis 3.500 jedoch eindeutig der Verbreitungsschwerpunkt. Der gesamte Brutvogelbestand Mitteleuropas lag zu Beginn des 21. Jahrhunderts bei 4.000 bis 6.000 Brutpaaren, davon ca. 1.000 bis 1.500 Brutv\u00f6gel in Deutschland.<\/p>\n<p>Das T\u00fcpfelsumpfhuhn z\u00e4hlt zu den Arten, f\u00fcr die eine deutliche Arealverschiebung infolge des Klimawandels vermutet wird. Ein Forschungsteam, das im Auftrag der britischen Umweltbeh\u00f6rde und der <a class=\"mw-redirect\" title=\"RSPB\" href=\"https:\/\/de.wikipedia.org\/wiki\/RSPB\">RSPB<\/a> die zuk\u00fcnftige Verbreitungsentwicklung von V\u00f6geln auf Basis von Klimamodellen untersuchte, geht davon aus, dass weite Teile des heutigen Verbreitungsgebietes dem T\u00fcpfelsumpfhuhn zuk\u00fcnftig keine geeigneten Lebensr\u00e4ume mehr bieten werden. Das Verbreitungsgebiet w\u00fcrde sich auf Basis dieser Prognosen deutlich nach Nordosten verschieben.<\/p>\n<p> <strong><img decoding=\"async\" class=\" size-full wp-image-5237\" src=\"http:\/\/wildtravel.ro\/wp-content\/uploads\/2017\/09\/aa_9.jpg\" alt=\"\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>foto:Mihai Baciu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das T\u00fcpfelsumpfhuhn (Porzana porzana) ist ein Vogel aus der Familie der Rallenv\u00f6gel. Es ist kleiner als eine Wasserralle und hat etwa die Gr\u00f6\u00dfe einer Drossel. Erscheinungsbild T\u00fcpfelsumpfh\u00fchner haben eine K\u00f6rperl\u00e4nge von etwa 19 bis 22,5 Zentimetern. Von den Wasserrallen k\u00f6nnen sie am einfachsten durch den kurzen, geraden Schnabel unterschieden werden. Dieser ist gelb mit einer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5242,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"birdwatching":[],"class_list":["post-5241","bird","type-bird","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00fcpfelsumpfhuhn (Porzana porzana) - Wilde Reise im Donaudelta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00fcpfelsumpfhuhn (Porzana porzana) - Wilde Reise im Donaudelta\" \/>\n<meta property=\"og:description\" content=\"Das T\u00fcpfelsumpfhuhn (Porzana porzana) ist ein Vogel aus der Familie der Rallenv\u00f6gel. Es ist kleiner als eine Wasserralle und hat etwa die Gr\u00f6\u00dfe einer Drossel. Erscheinungsbild T\u00fcpfelsumpfh\u00fchner haben eine K\u00f6rperl\u00e4nge von etwa 19 bis 22,5 Zentimetern. Von den Wasserrallen k\u00f6nnen sie am einfachsten durch den kurzen, geraden Schnabel unterschieden werden. Dieser ist gelb mit einer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/\" \/>\n<meta property=\"og:site_name\" content=\"Wilde Reise im Donaudelta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wildtravel.ro\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-18T15:47:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wildtravel.ro\/wp-content\/uploads\/2017\/09\/ac_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/\",\"url\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/\",\"name\":\"T\u00fcpfelsumpfhuhn (Porzana porzana) - Wilde Reise im Donaudelta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wildtravel.ro\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/ac_5.jpg\",\"datePublished\":\"2017-09-18T15:39:24+00:00\",\"dateModified\":\"2017-09-18T15:47:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wildtravel.ro\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/ac_5.jpg\",\"contentUrl\":\"https:\\\/\\\/wildtravel.ro\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/ac_5.jpg\",\"caption\":\"porzana porzana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/bird\\\/spotted-crake-porzana-porzana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wildtravel.ro\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Birds\",\"item\":\"https:\\\/\\\/wildtravel.ro\\\/ro\\\/bird\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00fcpfelsumpfhuhn (Porzana porzana)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/#website\",\"url\":\"https:\\\/\\\/wildtravel.ro\\\/\",\"name\":\"Wilde Reise im Donaudelta\",\"description\":\"Wild about wild\",\"publisher\":{\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wildtravel.ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/#organization\",\"name\":\"Wild travel\",\"url\":\"https:\\\/\\\/wildtravel.ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wildtravel.ro\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-125.png\",\"contentUrl\":\"http:\\\/\\\/wildtravel.ro\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-125.png\",\"width\":357,\"height\":125,\"caption\":\"Wild travel\"},\"image\":{\"@id\":\"https:\\\/\\\/wildtravel.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wildtravel.ro\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00fcpfelsumpfhuhn (Porzana porzana) - Wilde Reise im Donaudelta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/","og_locale":"de_DE","og_type":"article","og_title":"T\u00fcpfelsumpfhuhn (Porzana porzana) - Wilde Reise im Donaudelta","og_description":"Das T\u00fcpfelsumpfhuhn (Porzana porzana) ist ein Vogel aus der Familie der Rallenv\u00f6gel. Es ist kleiner als eine Wasserralle und hat etwa die Gr\u00f6\u00dfe einer Drossel. Erscheinungsbild T\u00fcpfelsumpfh\u00fchner haben eine K\u00f6rperl\u00e4nge von etwa 19 bis 22,5 Zentimetern. Von den Wasserrallen k\u00f6nnen sie am einfachsten durch den kurzen, geraden Schnabel unterschieden werden. Dieser ist gelb mit einer [&hellip;]","og_url":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/","og_site_name":"Wilde Reise im Donaudelta","article_publisher":"https:\/\/www.facebook.com\/wildtravel.ro\/","article_modified_time":"2017-09-18T15:47:11+00:00","og_image":[{"url":"https:\/\/wildtravel.ro\/wp-content\/uploads\/2017\/09\/ac_5.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/","url":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/","name":"T\u00fcpfelsumpfhuhn (Porzana porzana) - Wilde Reise im Donaudelta","isPartOf":{"@id":"https:\/\/wildtravel.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/#primaryimage"},"image":{"@id":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/#primaryimage"},"thumbnailUrl":"https:\/\/wildtravel.ro\/wp-content\/uploads\/2017\/09\/ac_5.jpg","datePublished":"2017-09-18T15:39:24+00:00","dateModified":"2017-09-18T15:47:11+00:00","breadcrumb":{"@id":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/#primaryimage","url":"https:\/\/wildtravel.ro\/wp-content\/uploads\/2017\/09\/ac_5.jpg","contentUrl":"https:\/\/wildtravel.ro\/wp-content\/uploads\/2017\/09\/ac_5.jpg","caption":"porzana porzana"},{"@type":"BreadcrumbList","@id":"https:\/\/wildtravel.ro\/bird\/spotted-crake-porzana-porzana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wildtravel.ro\/ro\/"},{"@type":"ListItem","position":2,"name":"Birds","item":"https:\/\/wildtravel.ro\/ro\/bird\/"},{"@type":"ListItem","position":3,"name":"T\u00fcpfelsumpfhuhn (Porzana porzana)"}]},{"@type":"WebSite","@id":"https:\/\/wildtravel.ro\/#website","url":"https:\/\/wildtravel.ro\/","name":"Wilde Reise im Donaudelta","description":"Wild about wild","publisher":{"@id":"https:\/\/wildtravel.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wildtravel.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wildtravel.ro\/#organization","name":"Wild travel","url":"https:\/\/wildtravel.ro\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wildtravel.ro\/#\/schema\/logo\/image\/","url":"http:\/\/wildtravel.ro\/wp-content\/uploads\/2023\/01\/logo-125.png","contentUrl":"http:\/\/wildtravel.ro\/wp-content\/uploads\/2023\/01\/logo-125.png","width":357,"height":125,"caption":"Wild travel"},"image":{"@id":"https:\/\/wildtravel.ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wildtravel.ro\/"]}]}},"_links":{"self":[{"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/bird\/5241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/bird"}],"about":[{"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/types\/bird"}],"author":[{"embeddable":true,"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/bird\/5241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/media\/5242"}],"wp:attachment":[{"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/media?parent=5241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/categories?post=5241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/tags?post=5241"},{"taxonomy":"birdwatching","embeddable":true,"href":"https:\/\/wildtravel.ro\/de\/wp-json\/wp\/v2\/birdwatching?post=5241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}